{"id":993,"date":"2025-04-15T16:15:38","date_gmt":"2025-04-15T14:15:38","guid":{"rendered":"http:\/\/wh.de.www302.your-server.de\/?page_id=993"},"modified":"2025-07-09T16:32:34","modified_gmt":"2025-07-09T14:32:34","slug":"products","status":"publish","type":"page","link":"https:\/\/wh.de\/en\/produkte\/","title":{"rendered":"Our Products"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"993\" class=\"elementor elementor-993\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-224c106 e-flex e-con-boxed e-con e-parent\" data-id=\"224c106\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a71fec elementor-widget elementor-widget-spacer\" data-id=\"7a71fec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-160b678a e-flex e-con-boxed e-con e-parent\" data-id=\"160b678a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77863c3b elementor-widget elementor-widget-heading\" data-id=\"77863c3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Product and Service overview<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f28dd37 e-flex e-con-boxed e-con e-parent\" data-id=\"f28dd37\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6effddf elementor-widget elementor-widget-text-editor\" data-id=\"6effddf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>We offer ready-to-use solutions for secure AC\/DC power supply in power plants, wind farms, solar parks, offshore plants, transformer stations, industry and in the field of rail traffic and transport.<\/strong><\/p><p>Switchgear is a highly complex system. A wide range of applications requires individual solutions. We are adapted to the requirements of different countries and network operators and are familiar with the respective standards. Use our specialist knowledge for new construction, further development and maintenance of your switchgear.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0b41c70 e-flex e-con-boxed e-con e-parent\" data-id=\"0b41c70\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6823606 e-con-full e-flex e-con e-child\" data-id=\"6823606\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9f6098 elementor-widget elementor-widget-image\" data-id=\"f9f6098\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"302\" src=\"https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/produkte-wechselrichter-1024x387.jpg\" class=\"attachment-large size-large wp-image-1019\" alt=\"Rectifier and inverter systems\" srcset=\"https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/produkte-wechselrichter-1024x387.jpg 1024w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/produkte-wechselrichter-300x113.jpg 300w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/produkte-wechselrichter-768x290.jpg 768w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/produkte-wechselrichter-18x7.jpg 18w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/produkte-wechselrichter.jpg 1139w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-146068e e-con-full e-flex e-con e-child\" data-id=\"146068e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4cae613 e-con-full e-flex e-con e-child\" data-id=\"4cae613\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-419e26f elementor-widget elementor-widget-text-editor\" data-id=\"419e26f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Rectifier and inverter systems<\/h2><p>They are used in transformer and power stations, in the telecommunications, railway and industrial sectors, or wherever secured voltages are required.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e14891b e-con-full e-flex e-con e-child\" data-id=\"e14891b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2441fca elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2441fca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wh.de\/en\/produkte\/gleich-und-wechselrichtersysteme\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bcd9561 e-flex e-con-boxed e-con e-parent\" data-id=\"bcd9561\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dfdaa6a e-con-full e-flex e-con e-child\" data-id=\"dfdaa6a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee7b0f1 elementor-widget elementor-widget-image\" data-id=\"ee7b0f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"302\" src=\"https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/thyristorgleichrichter-slider-1024x387.jpg\" class=\"attachment-large size-large wp-image-1059\" alt=\"Thyristor rectifiers\" srcset=\"https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/thyristorgleichrichter-slider-1024x387.jpg 1024w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/thyristorgleichrichter-slider-300x113.jpg 300w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/thyristorgleichrichter-slider-768x290.jpg 768w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/thyristorgleichrichter-slider-18x7.jpg 18w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/thyristorgleichrichter-slider.jpg 1139w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-775fc88 e-con-full e-flex e-con e-child\" data-id=\"775fc88\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-695cc3e e-con-full e-flex e-con e-child\" data-id=\"695cc3e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-56f4f09 elementor-widget elementor-widget-text-editor\" data-id=\"56f4f09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Thyristor rectifiers<\/h2><p>For high output power or robust applications, the thyristor rectifier is the most frequently used technology for protected direct current supply.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-77c3e29 e-con-full e-flex e-con e-child\" data-id=\"77c3e29\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c10de5c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c10de5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wh.de\/en\/produkte\/thyristorgleichrichter\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c845db5 e-flex e-con-boxed e-con e-parent\" data-id=\"c845db5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ceae394 e-con-full e-flex e-con e-child\" data-id=\"ceae394\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0799e80 elementor-widget elementor-widget-image\" data-id=\"0799e80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"302\" src=\"https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/usv-slider-1024x387.jpg\" class=\"attachment-large size-large wp-image-1063\" alt=\"Rectifier modules\" srcset=\"https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/usv-slider-1024x387.jpg 1024w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/usv-slider-300x113.jpg 300w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/usv-slider-768x290.jpg 768w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/usv-slider-18x7.jpg 18w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/usv-slider.jpg 1139w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-be996ae e-con-full e-flex e-con e-child\" data-id=\"be996ae\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4b66f5e e-con-full e-flex e-con e-child\" data-id=\"4b66f5e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2a9f66 elementor-widget elementor-widget-text-editor\" data-id=\"c2a9f66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Rectifier modules<\/h2><p>Rectifier modules from Westhaus Energietechnik GmbH are used in telecommunications, in industrial control systems and for charging and buffering stationary batteries in power and transformer stations.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fbf016e e-con-full e-flex e-con e-child\" data-id=\"fbf016e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-59e73ac elementor-align-center elementor-widget elementor-widget-button\" data-id=\"59e73ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wh.de\/en\/produkte\/gleichrichtermodule\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b1b6e5a e-flex e-con-boxed e-con e-parent\" data-id=\"b1b6e5a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c60b629 e-con-full e-flex e-con e-child\" data-id=\"c60b629\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e7a48f elementor-widget elementor-widget-image\" data-id=\"0e7a48f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"302\" src=\"https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/niederspannungs-schaltanlagen-slider1-1024x387.jpg\" class=\"attachment-large size-large wp-image-1070\" alt=\"Low-voltage switchgear\" srcset=\"https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/niederspannungs-schaltanlagen-slider1-1024x387.jpg 1024w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/niederspannungs-schaltanlagen-slider1-300x113.jpg 300w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/niederspannungs-schaltanlagen-slider1-768x290.jpg 768w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/niederspannungs-schaltanlagen-slider1-18x7.jpg 18w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/niederspannungs-schaltanlagen-slider1.jpg 1139w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-faf5a66 e-con-full e-flex e-con e-child\" data-id=\"faf5a66\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1154c7c e-con-full e-flex e-con e-child\" data-id=\"1154c7c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6fd4e90 elementor-widget elementor-widget-text-editor\" data-id=\"6fd4e90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Low-voltage switchgear<\/h2><p>Our LV switchgear is configured, manufactured and assembled by us according to your requirements. They offer safety and reliability at currents up to 4,000A.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d2d84c e-con-full e-flex e-con e-child\" data-id=\"1d2d84c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f821611 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f821611\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wh.de\/en\/produkte\/niederspannungs-schaltanlagen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63c701e e-flex e-con-boxed e-con e-parent\" data-id=\"63c701e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3f17b86 e-con-full e-flex e-con e-child\" data-id=\"3f17b86\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-573d0e1 elementor-widget elementor-widget-image\" data-id=\"573d0e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"302\" src=\"https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/usv-slider1-1024x387.jpg\" class=\"attachment-large size-large wp-image-1077\" alt=\"UPS-Systems\" srcset=\"https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/usv-slider1-1024x387.jpg 1024w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/usv-slider1-300x113.jpg 300w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/usv-slider1-768x290.jpg 768w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/usv-slider1-18x7.jpg 18w, https:\/\/wh.de\/wp-content\/uploads\/2025\/04\/usv-slider1.jpg 1139w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2034589 e-con-full e-flex e-con e-child\" data-id=\"2034589\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-9b6527d e-con-full e-flex e-con e-child\" data-id=\"9b6527d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d9627a elementor-widget elementor-widget-text-editor\" data-id=\"6d9627a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>UPS-Systems<\/h2><p>The uninterruptible power supply (UPS) serves as an interface between the supply network and the load, it guarantees continuity and high reliability in the power supply.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e2feecb e-con-full e-flex e-con e-child\" data-id=\"e2feecb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-269a08d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"269a08d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wh.de\/en\/produkte\/usv-anlagen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d3250ba e-flex e-con-boxed e-con e-parent\" data-id=\"d3250ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d3ba17 elementor-widget elementor-widget-spacer\" data-id=\"0d3ba17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Produkt- und Service-\u00dcberblick Wir bieten einsatzbereite L\u00f6sungen f\u00fcr gesicherte AC\/DC-Stromversorgung in Kraftwerken, Windparks, Solarparks, Offshore-Anlagen, Umspannwerken, Industrie und im Bereich Schienenverkehr und -transport. Schaltanlagen sind h\u00f6chst komplexe Systeme. Vielf\u00e4ltige Anwendungsbereiche erfordern individuelle L\u00f6sungen. Wir sind auf die Anforderungen unterschiedlicher L\u00e4nder und Netzbetreiber eingestellt und mit den jeweiligen Standards vertraut. Nutzen Sie unser Spezialwissen f\u00fcr den [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-993","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Produkte - Westhaus Energietechnik GmbH<\/title>\n<meta name=\"description\" content=\"Wir bieten einsatzbereite L\u00f6sungen f\u00fcr gesicherte AC\/DC-Stromversorgung in Kraftwerken, Windparks, Solarparks, Offshore-Anlagen, Umspannwerken, Industrie und im Bereich Schienenverkehr und -transport.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wh.de\/en\/products\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wh.de\\\/produkte\\\/\",\"url\":\"https:\\\/\\\/wh.de\\\/produkte\\\/\",\"name\":\"Produkte - Westhaus Energietechnik GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wh.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wh.de\\\/produkte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wh.de\\\/produkte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/neu.wh.de\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/produkte-wechselrichter-1024x387.jpg\",\"datePublished\":\"2025-04-15T14:15:38+00:00\",\"dateModified\":\"2025-07-09T14:32:34+00:00\",\"description\":\"Wir bieten einsatzbereite L\u00f6sungen f\u00fcr gesicherte AC\\\/DC-Stromversorgung in Kraftwerken, Windparks, Solarparks, Offshore-Anlagen, Umspannwerken, Industrie und im Bereich Schienenverkehr und -transport.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wh.de\\\/produkte\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wh.de\\\/produkte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/wh.de\\\/produkte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/neu.wh.de\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/produkte-wechselrichter-1024x387.jpg\",\"contentUrl\":\"https:\\\/\\\/neu.wh.de\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/produkte-wechselrichter-1024x387.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wh.de\\\/produkte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/wh.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wh.de\\\/#website\",\"url\":\"https:\\\/\\\/wh.de\\\/\",\"name\":\"Westhaus Energietechnik GmbH\",\"description\":\"Stromversorgungs- und Schaltanlagenbau\",\"publisher\":{\"@id\":\"https:\\\/\\\/wh.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wh.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wh.de\\\/#organization\",\"name\":\"Westhaus Energietechnik GmbH\",\"url\":\"https:\\\/\\\/wh.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/wh.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wh.de\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/WHDE-logo.png\",\"contentUrl\":\"https:\\\/\\\/wh.de\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/WHDE-logo.png\",\"width\":45,\"height\":45,\"caption\":\"Westhaus Energietechnik GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/wh.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Our products - Westhaus Energietechnik GmbH","description":"We offer ready-to-use solutions for secure AC\/DC power supply in power plants, wind farms, solar parks, offshore plants, transformer stations, industry and in the field of rail traffic and transport.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wh.de\/en\/products\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wh.de\/produkte\/","url":"https:\/\/wh.de\/produkte\/","name":"Our products - Westhaus Energietechnik GmbH","isPartOf":{"@id":"https:\/\/wh.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wh.de\/produkte\/#primaryimage"},"image":{"@id":"https:\/\/wh.de\/produkte\/#primaryimage"},"thumbnailUrl":"https:\/\/neu.wh.de\/wp-content\/uploads\/2025\/04\/produkte-wechselrichter-1024x387.jpg","datePublished":"2025-04-15T14:15:38+00:00","dateModified":"2025-07-09T14:32:34+00:00","description":"We offer ready-to-use solutions for secure AC\/DC power supply in power plants, wind farms, solar parks, offshore plants, transformer stations, industry and in the field of rail traffic and transport.","breadcrumb":{"@id":"https:\/\/wh.de\/produkte\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wh.de\/produkte\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/wh.de\/produkte\/#primaryimage","url":"https:\/\/neu.wh.de\/wp-content\/uploads\/2025\/04\/produkte-wechselrichter-1024x387.jpg","contentUrl":"https:\/\/neu.wh.de\/wp-content\/uploads\/2025\/04\/produkte-wechselrichter-1024x387.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/wh.de\/produkte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wh.de\/"},{"@type":"ListItem","position":2,"name":"Produkte"}]},{"@type":"WebSite","@id":"https:\/\/wh.de\/#website","url":"https:\/\/wh.de\/","name":"Westhaus Energietechnik GmbH","description":"Power supply and switchgear construction","publisher":{"@id":"https:\/\/wh.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wh.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/wh.de\/#organization","name":"Westhaus Energietechnik GmbH","url":"https:\/\/wh.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/wh.de\/#\/schema\/logo\/image\/","url":"https:\/\/wh.de\/wp-content\/uploads\/2020\/12\/WHDE-logo.png","contentUrl":"https:\/\/wh.de\/wp-content\/uploads\/2020\/12\/WHDE-logo.png","width":45,"height":45,"caption":"Westhaus Energietechnik GmbH"},"image":{"@id":"https:\/\/wh.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/wh.de\/en\/wp-json\/wp\/v2\/pages\/993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wh.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wh.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wh.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wh.de\/en\/wp-json\/wp\/v2\/comments?post=993"}],"version-history":[{"count":24,"href":"https:\/\/wh.de\/en\/wp-json\/wp\/v2\/pages\/993\/revisions"}],"predecessor-version":[{"id":1890,"href":"https:\/\/wh.de\/en\/wp-json\/wp\/v2\/pages\/993\/revisions\/1890"}],"wp:attachment":[{"href":"https:\/\/wh.de\/en\/wp-json\/wp\/v2\/media?parent=993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}